{"id":1047,"date":"2021-05-27T17:35:27","date_gmt":"2021-05-27T21:35:27","guid":{"rendered":"http:\/\/54.163.87.178\/?page_id=1047"},"modified":"2025-08-01T11:17:14","modified_gmt":"2025-08-01T15:17:14","slug":"hd-studies","status":"publish","type":"page","link":"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/hd-studies\/","title":{"rendered":"\u00c9tudes MH"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1047\" class=\"elementor elementor-1047\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-335e923 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"335e923\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59d1364\" data-id=\"59d1364\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d82f99b elementor-widget__width-auto elementor-widget elementor-widget-jkit_button\" data-id=\"d82f99b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-button  icon-position-after jeg_module___6a56ef5737c24\" ><a href=\"\/fr\/for-researchers\/\" class=\"jkit-button-wrapper\">Pour les chercheurs<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2628d69 elementor-widget__width-auto elementor-widget elementor-widget-jkit_button\" data-id=\"2628d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-button  icon-position-after jeg_module__1_6a56ef57387a8\" ><a href=\"#\" class=\"jkit-button-wrapper\">\u00c9tudes, donn\u00e9es, \u00e9chantillons biologiques<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79cb25c elementor-widget__width-auto elementor-widget elementor-widget-jkit_button\" data-id=\"79cb25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-button  icon-position-after jeg_module__2_6a56ef5739280\" ><a href=\"#\" class=\"jkit-button-wrapper\">\u00c9tudes MH<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a100da2 elementor-widget elementor-widget-spacer\" data-id=\"a100da2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f388f0 elementor-widget elementor-widget-heading\" data-id=\"7f388f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00c9tudes MH<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbbfa80 elementor-widget elementor-widget-text-editor\" data-id=\"dbbfa80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous trouverez ci-dessous une liste compl\u00e8te des \u00e9tudes MH initi\u00e9es par diff\u00e9rents sponsors \u00e0 partir de 1997. Pour chaque \u00e9tude, le promoteur, la dur\u00e9e de l'\u00e9tude, le statut, la taille de l'\u00e9chantillon et sa composition sont r\u00e9pertori\u00e9s, ainsi qu'un r\u00e9sum\u00e9 des types de donn\u00e9es disponibles.<\/p><p>Vous pouvez \u00e9galement parcourir directement <a href=\"\/fr\/for-researchers\/datasets\/\">les ensembles de donn\u00e9es cliniques<\/a>, <a href=\"\/fr\/for-researchers\/biosamples\/\">les \u00e9chantillons biologiques<\/a>, et <a href=\"\/fr\/for-researchers\/data-from-human-samples\/\">les ensembles de donn\u00e9es d'\u00e9chantillons biologiques<\/a> associ\u00e9s \u00e0 bon nombre de ces \u00e9tudes qui sont mises \u00e0 disposition via la plateforme Enroll-HD.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76da861 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"76da861\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-76da861\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4945\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/hd-studies\/\" class=\"elementor-item\">\u00c9tudes MH<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4971\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/datasets\/\" class=\"elementor-item\">Ensembles de donn\u00e9es cliniques<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4964\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/biosamples\/\" class=\"elementor-item\">\u00c9chantillons biologiques<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4980\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/data-from-human-samples\/\" class=\"elementor-item\">Donn\u00e9es provenant d\u2019\u00e9chantillons biologiques<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-76da861\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4945\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/hd-studies\/\" class=\"elementor-item\" tabindex=\"-1\">\u00c9tudes MH<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4971\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/datasets\/\" class=\"elementor-item\" tabindex=\"-1\">Ensembles de donn\u00e9es cliniques<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4964\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/biosamples\/\" class=\"elementor-item\" tabindex=\"-1\">\u00c9chantillons biologiques<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4980\"><a href=\"https:\/\/www.enroll-hd.org\/fr\/for-researchers\/data-from-human-samples\/\" class=\"elementor-item\" tabindex=\"-1\">Donn\u00e9es provenant d\u2019\u00e9chantillons biologiques<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ba75be4\" data-id=\"ba75be4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-415e13b elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"415e13b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-812dcc4\" data-id=\"812dcc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b8b569 elementor-widget elementor-widget-heading\" data-id=\"8b8b569\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9tudes MH<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ab7a86 elementor-widget elementor-widget-text-editor\" data-id=\"3ab7a86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Parcourez toutes les \u00e9tudes MH disponibles dans le tableau ci-dessous. Les \u00e9tudes peuvent \u00eatre tri\u00e9es en cliquant sur les en-t\u00eates de colonnes. Cliquez sur le nom de l'\u00e9tude pour obtenir des informations d\u00e9taill\u00e9es sur l'\u00e9tude. L'existence de donn\u00e9es cliniques, de donn\u00e9es d'imagerie, d'\u00e9chantillons biologiques et\/ou de donn\u00e9es d'\u00e9chantillons biologiques sp\u00e9cifiques \u00e0 l'\u00e9tude est indiqu\u00e9e par une coche verte\u00a0; veuillez cliquer sur le texte \u00ab\u00a0oui\u00a0\u00bb \u00e0 c\u00f4t\u00e9 de la coche pour plus d'informations sur la disponibilit\u00e9 et l'acc\u00e8s aux donn\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bcca0f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5bcca0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d639e31\" data-id=\"d639e31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c77d20 elementor-widget elementor-widget-html\" data-id=\"8c77d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\">app_id=\"5ef61b10f669390015306f73\";distribution_key=\"dist_5\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/loader.knack.com\/5ef61b10f669390015306f73\/dist_5\/knack.js\"><\/script><div id=\"knack-dist_5\">Chargement...<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>For Researchers Studies, Data, Biosamples HD Studies HD Studies Below is a comprehensive list of HD studies that have been initiated by different sponsors from 1997 onwards. For each study, the sponsor, study duration, status, sample size, and composition are listed, alongside a summary of available data types. You can also directly browse clinical datasets, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1060,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-1047","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/pages\/1047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/comments?post=1047"}],"version-history":[{"count":551,"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/pages\/1047\/revisions"}],"predecessor-version":[{"id":18260,"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/pages\/1047\/revisions\/18260"}],"up":[{"embeddable":true,"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/pages\/1060"}],"wp:attachment":[{"href":"https:\/\/www.enroll-hd.org\/fr\/wp-json\/wp\/v2\/media?parent=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}